{"id":31,"date":"2023-07-16T03:19:25","date_gmt":"2023-07-16T03:19:25","guid":{"rendered":"https:\/\/srtub.com\/?page_id=31"},"modified":"2024-07-03T02:47:49","modified_gmt":"2024-07-03T02:47:49","slug":"contato-srtub","status":"publish","type":"page","link":"https:\/\/srtub.com\/pt\/contato-srtub\/","title":{"rendered":"Contato Srtub"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>WhatsApp\/Wechat: +86 13075286997<br \/>\nE-mail: sales@srtub.com<\/p>\n<p style=\"text-align: center;\">\n<\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f57-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"57\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/pages\/31#wpcf7-f57-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/31#wpcf7-f57-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"57\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f57-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Nome<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Telefone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span> <\/label>\n<\/p>\n<p><label> Mensagem<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua consulta\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"189\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Fechar\">\u00d7<\/button><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n<div class=\"fusion-text fusion-text-2\"><h2 style=\"text-align: center;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>F\u00e1brica de tubos de silicone Srtub<\/strong><\/h2>\n<p>Com mais de 22 anos de experi\u00eancia, a SRTUB Silicone Tube Factory \u00e9 uma empresa especializada em pesquisa e desenvolvimento, produ\u00e7\u00e3o e vendas de v\u00e1rios produtos de silicone de alta qualidade e precis\u00e3o, tendo passado pela certifica\u00e7\u00e3o BV com sua pr\u00f3pria f\u00e1brica.<\/p>\n<p>A Srtub possui certificados completos. Nosso tubo de silicone para uso m\u00e9dico e o tubo de silicone para bomba perist\u00e1ltica s\u00e3o extrudados com mat\u00e9rias-primas importadas de borracha de silicone curada com platina.<\/p>\n<p>Nossos principais produtos incluem tubos de silicone de grau aliment\u00edcio, tubos de silicone para uso m\u00e9dico, tubos de silicone para bombas perist\u00e1lticas, produtos moldados e outros tubos de silicone.<\/p>\n<p>A personaliza\u00e7\u00e3o profissional de v\u00e1rios tubos de silicone, como tubos de silicone de grau m\u00e9dico, tubos de silicone de grau aliment\u00edcio, tubos de bomba perist\u00e1ltica, luvas de LED, tubos de silicone industriais, etc.<\/p>\n<p>Nossa empresa tamb\u00e9m pode produzir an\u00e9is de veda\u00e7\u00e3o de silicone e correias de carga de silicone,<br \/>\ntiras de silicone, produtos de silicone moldado (bandejas de gelo de silicone, envolt\u00f3rio de silicone),<br \/>\nmolde de silicone, etc.<\/p>\n<p>Temos uma coopera\u00e7\u00e3o de longo prazo com mais de 5.000 parceiros de todo o mundo.<br \/>\nContanto que voc\u00ea venha at\u00e9 n\u00f3s com suas necessidades, faremos o melhor que pudermos para alcan\u00e7ar infinitas possibilidades!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-21 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1.jpg\" alt=\"O melhor tubo de silicone de todos os tempos - Sprtub\" width=\"1920\" height=\"750\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-18x7.jpg 18w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-200x78.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-300x117.jpg 300w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-400x156.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-500x195.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-600x234.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-700x273.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-768x300.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-800x313.jpg 800w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-1024x400.jpg 1024w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-1200x469.jpg 1200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1-1536x600.jpg 1536w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-1.jpg 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-22 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2.jpg\" alt=\"O melhor tubo de silicone de todos os tempos - Sprtub\" width=\"1920\" height=\"750\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-18x7.jpg 18w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-200x78.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-300x117.jpg 300w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-400x156.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-500x195.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-600x234.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-700x273.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-768x300.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-800x313.jpg 800w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-1024x400.jpg 1024w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-1200x469.jpg 1200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2-1536x600.jpg 1536w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-2.jpg 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<h4><strong>Balan\u00e7a de f\u00e1brica Srtub<\/strong><\/h4>\n<p>Estamos equipados com 1.000 m\u00b2 de sala limpa m\u00e9dica de 100 mil classes e 1.500 m\u00b2 de oficina limpa padr\u00e3o.<\/p>\n<h4><strong>Qualidade do produto<\/strong><\/h4>\n<p>Supervisione rigorosamente a inspe\u00e7\u00e3o de qualidade das mat\u00e9rias-primas, da produ\u00e7\u00e3o e da qualidade do produto para garantir que a taxa de aprova\u00e7\u00e3o dos produtos seja superior a 98%.<\/p>\n<h4><strong>Escopo de neg\u00f3cios da Srtub<\/strong><\/h4>\n<p>Nossos principais produtos incluem tubos de silicone de grau aliment\u00edcio, tubos de silicone para uso m\u00e9dico, tubos de silicone para bombas perist\u00e1lticas, produtos moldados e outros tipos de silicone<\/p>\n<h4><strong>Equipe Srtub<\/strong><\/h4>\n<p>Com a filosofia de \"servi\u00e7os profissionais, de precis\u00e3o, alta efici\u00eancia, alta qualidade, inova\u00e7\u00e3o e integridade\", sempre aderimos ao atendimento ao cliente.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-45 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1.jpg\" alt=\"F\u00e1brica de tubos de silicone Srtub\" width=\"800\" height=\"800\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-12x12.jpg 12w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-66x66.jpg 66w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-150x150.jpg 150w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-200x200.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-300x300.jpg 300w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-400x400.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-500x500.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-600x600.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-700x700.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1-768x768.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-1.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-46 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2.jpg\" alt=\"F\u00e1brica de tubos de silicone Srtub\" width=\"784\" height=\"960\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-10x12.jpg 10w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-200x245.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-245x300.jpg 245w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-400x490.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-500x612.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-600x735.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-700x857.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2-768x940.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-2.jpg 784w\" sizes=\"(max-width: 784px) 100vw, 784px\" \/><\/p>\n<p><div id=\"attachment_47\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-47\" class=\"wp-image-47 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3.jpg\" alt=\"F\u00e1brica de tubos de silicone Srtub\" width=\"800\" height=\"800\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-12x12.jpg 12w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-66x66.jpg 66w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-150x150.jpg 150w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-200x200.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-300x300.jpg 300w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-400x400.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-500x500.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-600x600.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-700x700.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3-768x768.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-3.jpg 800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-47\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><strong>Parceiros Srtub<\/strong><\/span><\/p><\/div>\n<div id=\"attachment_23\" style=\"width: 1930px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23\" class=\"wp-image-23 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3.jpg\" alt=\"O melhor tubo de silicone de todos os tempos - Sprtub\" width=\"1920\" height=\"750\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-18x7.jpg 18w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-200x78.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-300x117.jpg 300w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-400x156.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-500x195.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-600x234.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-700x273.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-768x300.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-800x313.jpg 800w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-1024x400.jpg 1024w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-1200x469.jpg 1200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3-1536x600.jpg 1536w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Best-Silicone-Tube-Ever-Srtub-3.jpg 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><p id=\"caption-attachment-23\" class=\"wp-caption-text\"><strong><span style=\"color: #000000;\">Por que escolher a Srtub?<\/span><\/strong><\/p><\/div>\n<div id=\"attachment_48\" style=\"width: 760px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48\" class=\"wp-image-48 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4.jpg\" alt=\"F\u00e1brica de tubos de silicone Srtub\" width=\"750\" height=\"617\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-15x12.jpg 15w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-200x165.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-300x247.jpg 300w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-400x329.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-500x411.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-600x494.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4-700x576.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-4.jpg 750w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><p id=\"caption-attachment-48\" class=\"wp-caption-text\"><span style=\"color: #000000;\"><strong>Embalagem e envio do tubo de silicone Srtub<\/strong><\/span><\/p><\/div>\n<div id=\"attachment_49\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-49\" class=\"wp-image-49 size-full\" src=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5.jpg\" alt=\"F\u00e1brica de tubos de silicone Srtub\" width=\"790\" height=\"816\" srcset=\"https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-12x12.jpg 12w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-200x207.jpg 200w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-290x300.jpg 290w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-400x413.jpg 400w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-500x516.jpg 500w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-600x620.jpg 600w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-700x723.jpg 700w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5-768x793.jpg 768w, https:\/\/srtub.com\/wp-content\/uploads\/2023\/07\/Srtub-Silicone-Tube-Factory-5.jpg 790w\" sizes=\"(max-width: 790px) 100vw, 790px\" \/><p id=\"caption-attachment-49\" class=\"wp-caption-text\"><strong>FAQ da Srtub<\/strong><\/p><\/div><\/p>\n<p>1.  Posso obter a amostra?<br \/>\nSim, podemos lhe fornecer amostras gratuitas, mas cobramos uma pequena taxa de amostra para projetos personalizados. Os novos clientes devem pagar pelo custo de entrega, e a taxa de amostra ser\u00e1 deduzida do pagamento dos pedidos formais.<br \/>\n2. Qual \u00e9 o prazo de entrega da amostra?<br \/>\nPara produtos existentes, leva de 1 a 2 dias; se voc\u00ea quiser seu design, pode levar de 3 a 5 dias, dependendo do conte\u00fado do design.<br \/>\n3.  Como \u00e9 o controle de qualidade do seu produto?<br \/>\nTemos um departamento de controle de qualidade com uma equipe profissional de controle de qualidade.  \"Qualidade em primeiro lugar, foco no cliente\" \u00e9 a nossa pol\u00edtica de qualidade, e temos controle de qualidade de entrada\/controle de qualidade em processo\/controle de qualidade de sa\u00edda em todas as opera\u00e7\u00f5es da nossa f\u00e1brica.<br \/>\n4.  Por que devo comprar seu tubo de silicone?<br \/>\nNosso tubo de silicone oferece excelente qualidade, pre\u00e7o razo\u00e1vel, bom servi\u00e7o p\u00f3s-venda e garantia de qualidade.<br \/>\nWhatsApp\/Wechat: +86 13075286997<br \/>\nE-mail: sales@srtub.com<\/p>\n<\/div>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f57-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"57\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pt\/wp-json\/wp\/v2\/pages\/31#wpcf7-f57-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contato\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/pt\/wp-json\/wp\/v2\/pages\/31#wpcf7-f57-o2\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"57\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.2\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f57-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Nome<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Telefone<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span> <\/label>\n<\/p>\n<p><label> Mensagem<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envie sua consulta\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"200\"\/><script>document.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output awb-alert-native-link-color alert-dismissable awb-alert-close-boxed\" style=\"--awb-border-size:1px;--awb-border-top-left-radius:0px;--awb-border-top-right-radius:0px;--awb-border-bottom-left-radius:0px;--awb-border-bottom-right-radius:0px;\" role=\"alert\"><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><button type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-label=\"Fechar\">\u00d7<\/button><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"pt\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":{"view":"yes"},"footnotes":""},"class_list":["post-31","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/pages\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":7,"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/pages\/31\/revisions"}],"predecessor-version":[{"id":522,"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/pages\/31\/revisions\/522"}],"wp:attachment":[{"href":"https:\/\/srtub.com\/pt\/wp-json\/wp\/v2\/media?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}